{"id":1960,"date":"2025-08-21T02:23:45","date_gmt":"2025-08-21T02:23:45","guid":{"rendered":"https:\/\/haytrix-display.com\/?post_type=product&#038;p=1960"},"modified":"2025-10-16T02:14:12","modified_gmt":"2025-10-16T02:14:12","slug":"haytrix-m6h-e-fahrrad-e-scooter-display","status":"publish","type":"product","link":"https:\/\/www.haytrix-display.com\/de\/product\/haytrix-m6h-e-bike-e-scooter-display\/","title":{"rendered":"Haytrix M6H E-Bike &amp; E-Scooter Anzeige - UART No.2 Protokoll | B2B Smart Dashboard"},"content":{"rendered":"<p data-start=\"515\" data-end=\"816\">Die <strong data-start=\"519\" data-end=\"542\">Haytrix M6H Anzeige<\/strong> ist ein intelligentes Armaturenbrett der n\u00e4chsten Generation, das f\u00fcr <strong data-start=\"590\" data-end=\"621\">elektrische Fahrr\u00e4der und Roller<\/strong>, die sowohl in der OEM-Fertigung als auch auf dem Ersatzteilmarkt weit verbreitet sind. Mit <strong data-start=\"692\" data-end=\"728\">UART No.2 Kommunikationsprotokoll<\/strong>, Der M6H bietet reibungslose Konnektivit\u00e4t, umfassende Systemkompatibilit\u00e4t und einfache Integration.<\/p>\n<p data-start=\"818\" data-end=\"847\"><strong data-start=\"818\" data-end=\"845\">Warum Haytrix M6H w\u00e4hlen?<\/strong><\/p>\n<ul data-start=\"848\" data-end=\"1478\">\n<li data-start=\"848\" data-end=\"971\">\n<p data-start=\"850\" data-end=\"971\"><strong data-start=\"850\" data-end=\"873\">UART Nr.2 Protokoll:<\/strong> Gew\u00e4hrleistet eine stabile Daten\u00fcbertragung und Kompatibilit\u00e4t mit den wichtigsten E-Bike- und E-Scooter-Steuerger\u00e4ten.<\/p>\n<\/li>\n<li data-start=\"972\" data-end=\"1074\">\n<p data-start=\"974\" data-end=\"1074\"><strong data-start=\"974\" data-end=\"995\">Breite Anwendung:<\/strong> Geeignet f\u00fcr OEM-Produktion, Gro\u00dfhandel und kleine Werkst\u00e4tten.<\/p>\n<\/li>\n<li data-start=\"1075\" data-end=\"1175\">\n<p data-start=\"1077\" data-end=\"1175\"><strong data-start=\"1077\" data-end=\"1107\">Klarer und funktionaler Bildschirm:<\/strong> Zeigt Geschwindigkeit, Batteriestand, Fahrtinformationen und Fahrdaten an.<\/p>\n<\/li>\n<li data-start=\"1176\" data-end=\"1267\">\n<p data-start=\"1178\" data-end=\"1267\"><strong data-start=\"1178\" data-end=\"1200\">Starke Best\u00e4ndigkeit:<\/strong> Wasser- und staubdichtes Geh\u00e4use f\u00fcr den langfristigen Einsatz im Freien.<\/p>\n<\/li>\n<li data-start=\"1268\" data-end=\"1377\">\n<p data-start=\"1270\" data-end=\"1377\"><strong data-start=\"1270\" data-end=\"1292\">B2B-Anpassung:<\/strong> Erh\u00e4ltlich mit optionalen Funktionen wie Codesperre und Killswitch f\u00fcr Gro\u00dfauftr\u00e4ge.<\/p>\n<\/li>\n<li data-start=\"1378\" data-end=\"1478\">\n<p data-start=\"1380\" data-end=\"1478\"><strong data-start=\"1380\" data-end=\"1402\">Einfache Installation:<\/strong> Die Plug-and-Play-Schnittstelle reduziert die Einrichtungszeit f\u00fcr Werkst\u00e4tten und Servicezentren.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1480\" data-end=\"1657\">Die <strong data-start=\"1484\" data-end=\"1499\">Haytrix M6H<\/strong> ist die richtige Wahl f\u00fcr <strong data-start=\"1524\" data-end=\"1596\">Hersteller, Distributoren, E-Bike-H\u00e4ndler und Dienstleistungsanbieter<\/strong> auf der Suche nach einem Profi <strong data-start=\"1624\" data-end=\"1645\">B2B-Smart-Display<\/strong> L\u00f6sung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die <strong data-start=\"257\" data-end=\"280\">Haytrix M6H Anzeige<\/strong> ist ein robustes, intelligentes Armaturenbrett f\u00fcr E-Bikes und E-Scooter, das <strong data-start=\"344\" data-end=\"366\">UART-Protokoll Nr. 2<\/strong> f\u00fcr zuverl\u00e4ssige Leistung. Entwickelt f\u00fcr Hersteller, H\u00e4ndler und Werkst\u00e4tten.<\/p>","protected":false},"featured_media":1961,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[23],"product_cat":[39],"product_tag":[56,53,50,57,70,131,138,69,55,35],"class_list":{"0":"post-1960","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-haytrix","7":"product_cat-conventional-display-customizable","8":"product_tag-b2b-e-mobility","9":"product_tag-e-bike-dashboard","10":"product_tag-e-scooter-display","11":"product_tag-electric-bike-accessory","12":"product_tag-electric-scooter-parts","13":"product_tag-haytrix-display","14":"product_tag-haytrix-m6h","15":"product_tag-m6h-display","16":"product_tag-smart-display","17":"product_tag-uart-no-2","18":"desktop-align-left","19":"tablet-align-left","20":"mobile-align-left","22":"first","23":"instock","24":"shipping-taxable","25":"purchasable","26":"product-type-variable"},"spectra_custom_meta":{"surerank_seo_checks":["a:10:{s:14:\"h2_subheadings\";a:2:{s:6:\"status\";s:7:\"warning\";s:7:\"message\";s:42:\"The page does not contain any subheadings.\";}s:13:\"media_present\";a:2:{s:6:\"status\";s:7:\"success\";s:7:\"message\";s:55:\"This page includes images or videos to enhance content.\";}s:13:\"links_present\";a:2:{s:6:\"status\";s:7:\"warning\";s:7:\"message\";s:27:\"No links found on the page.\";}s:10:\"url_length\";a:2:{s:6:\"status\";s:7:\"success\";s:7:\"message\";s:35:\"Page URL is short and SEO-friendly.\";}s:19:\"search_engine_title\";a:2:{s:6:\"status\";s:7:\"warning\";s:7:\"message\";s:42:\"Search engine title exceeds 60 characters.\";}s:25:\"search_engine_description\";a:2:{s:6:\"status\";s:7:\"success\";s:7:\"message\";s:62:\"Search engine description is present and under 160 characters.\";}s:13:\"canonical_url\";a:2:{s:6:\"status\";s:7:\"success\";s:7:\"message\";s:37:\"Canonical tag is present on the page.\";}s:15:\"open_graph_tags\";a:2:{s:6:\"status\";s:7:\"success\";s:7:\"message\";s:40:\"Open Graph tags are present on the page.\";}s:12:\"broken_links\";a:2:{s:6:\"status\";s:7:\"success\";s:7:\"message\";s:34:\"No broken links found on the page.\";}s:14:\"image_alt_text\";a:4:{s:6:\"status\";s:7:\"warning\";s:11:\"description\";a:2:{i:0;s:37:\"The page does not contain any images.\";i:1;s:60:\"Add images to improve the post\/page's visual appeal and SEO.\";}s:7:\"message\";s:64:\"One or more images on this page are missing alt text attributes.\";s:11:\"show_images\";b:0;}}"],"surerank_seo_checks_last_updated":["1755842080"],"_edit_last":["1"],"_edit_lock":["1760580760:1"],"total_sales":["0"],"_tax_status":["taxable"],"_tax_class":[""],"_manage_stock":["no"],"_backorders":["no"],"_sold_individually":["no"],"_virtual":["no"],"_downloadable":["no"],"_download_limit":["-1"],"_download_expiry":["-1"],"_stock":[null],"_stock_status":["instock"],"_wc_average_rating":["0"],"_wc_review_count":["0"],"_product_attributes":["a:1:{s:23:\"interface-typeuart-no-2\";a:6:{s:4:\"name\";s:25:\"Interface Type(UART NO.2)\";s:5:\"value\";s:38:\"5pin | 6pin | sm5pin | sm6pin | sm7pin\";s:8:\"position\";i:0;s:10:\"is_visible\";i:1;s:12:\"is_variation\";i:1;s:11:\"is_taxonomy\";i:0;}}"],"_product_version":["10.2.2"],"_price":["21"],"rank_math_internal_links_processed":["1"],"rank_math_contentai_score":["a:5:{s:8:\"keywords\";s:5:\"74.51\";s:9:\"wordCount\";s:1:\"0\";s:9:\"linkCount\";s:1:\"0\";s:12:\"headingCount\";s:1:\"0\";s:10:\"mediaCount\";s:1:\"0\";}"],"rank_math_seo_score":["25"],"rank_math_title":["Haytrix M6H Display for E-Bike &amp; E-Scooter \u2013 UART No.2 Smart Dashboard | B2B"],"rank_math_description":["Buy the Haytrix M6H display with UART No.2 protocol for e-bikes and e-scooters. Clear, durable, and customizable. Ideal for B2B suppliers, OEMs, and repair shops."],"rank_math_focus_keyword":["UART No.2 display,e-bike display,e-scooter dashboard,B2B smart display,Haytrix M6H"],"_thumbnail_id":["1961"],"_product_image_gallery":["1962,1963,1964,1965,1966,1967"],"rank_math_primary_product_brand":["23"],"rank_math_primary_product_cat":["39"],"site-sidebar-layout":["default"],"ast-site-content-layout":["default"],"site-content-style":["default"],"site-sidebar-style":["default"],"theme-transparent-header-meta":["default"],"rank_math_analytic_object_id":["10"],"_aipkit_openai_file_id_for_vs_vs_68cb9d577640819193302a9ba797ee09":["file-GDokaJkSWw2kPRTDRaUHdF"],"_aipkit_indexed_to_vs_vs_68cb9d577640819193302a9ba797ee09":["1"],"_wp_old_slug":["haytric-m6h-e-bike-e-scooter-display"],"_aipkit_is_token_package":["no"],"astra-migrate-meta-layouts":["set"],"_uag_css_file_name":["uag-css-1960.css"],"_uag_js_file_name":["uag-js-1960.js"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:61132:\".wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-advanced-heading.uagb-block-10679260.wp-block-uagb-advanced-heading {margin-bottom: -13px;}.wp-block-uagb-advanced-heading.uagb-block-10679260.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-10679260.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-10679260.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-10679260.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-10679260 .uagb-heading-text{font-weight: 100;font-size: 20px;line-height: 30px;}@media only screen and (max-width: 767px) {.wp-block-uagb-advanced-heading.uagb-block-10679260.wp-block-uagb-advanced-heading {margin-bottom: -20px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-container.uagb-block-bc1c5960 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bc1c5960 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bc1c5960 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bc1c5960 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bc1c5960 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc1c5960{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc1c5960 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bc1c5960{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc1c5960{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc1c5960 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bc1c5960{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-bc1c5960{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bc1c5960 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bc1c5960{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-heading-text{color: rgba(0,0,0,0.6);}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-heading-text{color: rgba(0,0,0,0.6);}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-heading-text{color: rgba(0,0,0,0.6);}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-heading-text{color: rgba(0,0,0,0.6);}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-heading-text{color: rgba(0,0,0,0.6);}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7e480da4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-blockquote{padding:0;margin:0 auto;-webkit-box-sizing:border-box;box-sizing:border-box}.wp-block-uagb-blockquote .uagb-blockquote__content,.wp-block-uagb-blockquote cite.uagb-blockquote__author{display:block;font-style:normal}.wp-block-uagb-blockquote cite.uagb-blockquote__author,.wp-block-uagb-blockquote .uagb-blockquote__author{-ms-flex-item-align:center;align-self:center}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation blockquote.uagb-blockquote{margin:0;padding:0;border:0;outline:0;font-size:100%;vertical-align:baseline;background:rgba(0,0,0,0);quotes:none;border-left:0 none;border-right:0 none;border-top:0 none;border-bottom:0 none;font-style:normal}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{display:inline-flex;float:unset}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap .uagb-blockquote__icon{padding:0;margin-right:0;margin-bottom:0}.wp-block-uagb-blockquote .uagb-blockquote__skin-quotation.uagb-blockquote__style-style_2 .uagb-blockquote__icon-wrap{display:inline-block;float:left}.wp-block-uagb-blockquote .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{background-color:#1da1f2;border-radius:100em;color:#fff}.wp-block-uagb-blockquote .uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote .uagb-blockquote__tweet-text a.uagb-blockquote__tweet-button{padding:10px 14px}.wp-block-uagb-blockquote .uagb-blockquote__with-tweet.uagb-blockquote__align-center .uagb-blockquote footer,.wp-block-uagb-blockquote .uagb-blockquote__align-center .uagb-blockquote footer{display:block;text-align:center}.wp-block-uagb-blockquote .uagb-blockquote__align-center .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__align-center.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.wp-block-uagb-blockquote .uagb-blockquote__align-center a.uagb-blockquote__tweet-button{display:block;text-align:center;margin:0 auto;-ms-flex-item-align:center;align-self:center}.wp-block-uagb-blockquote .uagb-blockquote__with-tweet .uagb-blockquote footer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;-webkit-box-pack:justify;-webkit-justify-content:space-between;-ms-flex-pack:justify;justify-content:space-between}.wp-block-uagb-blockquote .uagb-blockquote__with-tweet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{width:auto;align-items:center}.wp-block-uagb-blockquote .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{position:absolute;top:50%;left:-0.8em;border:solid .5em rgba(0,0,0,0);border-right-color:#1da1f2;transform:translateY(-50%) scale(1, 0.65);transition:.2s;content:\"\";-webkit-transform:translateY(-50%) scale(1, 0.65);-ms-transform:translateY(-50%) scale(1, 0.65);-webkit-transition:.2s;-o-transition:.2s}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation blockquote.uagb-blockquote{vertical-align:baseline;padding:0;margin:0;background:rgba(0,0,0,0);border:0 none;outline:0;font-size:100%;font-style:normal;quotes:none}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation .uagb-blockquote__icon{position:relative;display:inline-block;z-index:1;padding:10px;margin-right:10px;border-radius:100%;float:left}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{display:inherit;width:inherit;height:inherit}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation.uagb-blockquote__style-style_2.uagb-blockquote__align-right .uagb-blockquote__icon{display:inline-block;float:right}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation.uagb-blockquote__style-style_2 .uagb-blockquote__icon{display:inline-block;float:left}.wp-block-uagb-blockquote.uagb-blockquote__skin-quotation.uagb-blockquote__style-style_1 .uagb-blockquote__icon{display:inline-flex;float:unset}.wp-block-uagb-blockquote blockquote.uagb-blockquote{padding:0;margin:0}.wp-block-uagb-blockquote .uagb-blockquote__style-style_2 .uagb-blockquote__icon{display:inline-block;float:left;text-align:left}.wp-block-uagb-blockquote .uagb-blockquote__separator-parent{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;justify-content:flex-start;-js-display:flex;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet .uagb-blockquote footer{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;justify-content:space-between;-webkit-box-pack:justify;-webkit-justify-content:space-between;-ms-flex-pack:justify}.wp-block-uagb-blockquote .uagb-blockquote a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.wp-block-uagb-blockquote .uagb-blockquote a.uagb-blockquote__tweet-button{position:relative;display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;align-self:center;width:-webkit-max-content;width:-moz-max-content;width:max-content;padding:0;background-color:rgba(0,0,0,0);color:#1da1f2;line-height:1;transition:.2s;-webkit-transition:.2s;-o-transition:.2s;-webkit-align-self:flex-end;-ms-flex-item-align:center}.wp-block-uagb-blockquote a.uagb-blockquote__tweet-button svg{align-self:center;vertical-align:middle;width:15px;height:15px;fill:#fff}.wp-block-uagb-blockquote a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote a.uagb-blockquote__tweet-button svg{font-style:normal}.wp-block-uagb-blockquote.uagb-blockquote__tweet-icon a.uagb-blockquote__tweet-button svg{margin-right:0}.wp-block-uagb-blockquote.uagb-blockquote__tweet-icon a.uagb-blockquote__tweet-button{padding:8px}.wp-block-uagb-blockquote.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote.uagb-blockquote__tweet-text a.uagb-blockquote__tweet-button{padding:10px 14px}.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{padding:10px 0}.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button,.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{background-color:#1da1f2;border-radius:100em;color:#fff}.wp-block-uagb-blockquote.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{position:absolute;top:50%;left:-0.8em;border:solid .5em rgba(0,0,0,0);border-right-color:#1da1f2;transform:translateY(-50%) scale(1, 0.65);transition:.2s;content:\"\";-webkit-transform:translateY(-50%) scale(1, 0.65);-ms-transform:translateY(-50%) scale(1, 0.65);-webkit-transition:.2s;-o-transition:.2s}.wp-block-uagb-blockquote.uagb-blockquote__align-right.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{right:-0.8em;left:auto;transform:translateY(-50%) scale(1, 0.65) rotate(180deg);-webkit-transform:translateY(-50%) scale(1, 0.65) rotate(180deg);-ms-transform:translateY(-50%) scale(1, 0.65) rotate(180deg)}.wp-block-uagb-blockquote.uagb-blockquote__align-center.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{top:-0.8em;right:auto;left:50%;transform:translate(-50%, 10%) scale(1, 0.85) rotate(90deg);-webkit-transform:translateX(-50%) scale(1, 0.85) rotate(90deg);-ms-transform:translateX(-50%) scale(1, 0.85) rotate(90deg)}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet.uagb-blockquote__align-center .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote footer{display:block;text-align:center}.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right,.wp-block-uagb-blockquote.uagb-blockquote__align-center.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.wp-block-uagb-blockquote.uagb-blockquote__align-center a.uagb-blockquote__tweet-button{display:block;align-self:center;margin:0 auto;text-align:center;-ms-flex-item-align:center}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet.uagb-blockquote__align-right .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote footer{flex-direction:row-reverse}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap{display:-webkit-box;display:-webkit-flex;display:-ms-flexbox;display:flex;flex-direction:row;align-self:center;align-items:center}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap img{width:50px;height:50px;border-radius:100%;object-fit:cover}.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote.uagb-blockquote__align-left .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right{justify-content:flex-end;-webkit-box-pack:flex-end;-ms-flex-pack:flex-end;-webkit-justify-content:flex-end;-moz-box-pack:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__align-left .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right{justify-content:flex-start;-webkit-box-pack:flex-start;-ms-flex-pack:flex-start;-webkit-justify-content:flex-start;-moz-box-pack:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:unset;-webkit-box-pack:unset;-ms-flex-pack:unset;-webkit-justify-content:unset;-moz-box-pack:unset}.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote.uagb-blockquote__align-center.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap{justify-content:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{flex-direction:column;width:100%;-webkit-flex-direction:column;-ms-flex-direction:column;align-items:flex-start}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top .uagb-blockquote__author{width:inherit}.wp-block-uagb-blockquote.uagb-blockquote__with-tweet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{width:auto}.wp-block-uagb-blockquote.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{text-align:right;align-items:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__align-center .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top{text-align:center;align-items:center}.wp-block-uagb-blockquote .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right{-webkit-flex-direction:row-reverse;-ms-flex-direction:row-reverse;flex-direction:row-reverse;justify-content:flex-end}@media only screen and (max-width: 976px){.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author{width:100%}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-items:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__with-tweet .uagb-blockquote footer{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-self:flex-start;-ms-flex-item-align:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-start;align-self:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right.uagb-blockquote__with-tweet .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-right.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-tablet.uagb-blockquote__align-left.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{top:-0.8em;right:auto;left:50%;transform:translate(-50%, 10%) scale(1, 0.85) rotate(90deg);-webkit-transform:translateX(-50%) scale(1, 0.85) rotate(90deg);-ms-transform:translateX(-50%) scale(1, 0.85) rotate(90deg)}.wp-block-uagb-blockquote .uagb-blockquote__align-right.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-tablet .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-tablet .uagb-blockquote__author{-ms-flex-item-align:flex-start;align-self:flex-start}}@media screen and (max-width: 767px){.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author{width:100%}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-items:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__with-tweet .uagb-blockquote footer{-webkit-flex-direction:column;-ms-flex-direction:column;flex-direction:column;align-self:flex-start;-ms-flex-item-align:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-start;align-self:flex-start}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right.uagb-blockquote__with-tweet .uagb-blockquote footer,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right a.uagb-blockquote__tweet-button{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-right.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before,.wp-block-uagb-blockquote.uagb-blockquote__stack-img-mobile.uagb-blockquote__align-left.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button::before{top:-0.8em;right:auto;left:50%;transform:translate(-50%, 10%) scale(1, 0.85) rotate(90deg);-webkit-transform:translateX(-50%) scale(1, 0.85) rotate(90deg);-ms-transform:translateX(-50%) scale(1, 0.85) rotate(90deg)}.wp-block-uagb-blockquote .uagb-blockquote__align-right.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap{-ms-flex-item-align:flex-end;align-self:flex-end}.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-mobile .uagb-blockquote__author-wrap,.wp-block-uagb-blockquote .uagb-blockquote__align-left.uagb-blockquote__stack-img-tablet .uagb-blockquote__author{-ms-flex-item-align:flex-start;align-self:flex-start}}.uagb-block-04b261ae .uagb-blockquote__content{font-style: italic;font-size: 18px;line-height: 1.5em;margin-bottom: 25px;text-align: left;}.uagb-block-04b261ae cite.uagb-blockquote__author{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon{width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{width: 25px;height: 25px;fill: #3d3d3d;}.uagb-block-04b261ae.uagb-blockquote__style-style_1 .uagb-blockquote{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 40px;height: 40px;border-radius: 100%;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{fill: #3d3d3d;width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__align-center blockquote.uagb-blockquote{text-align: left;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button svg{fill: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae a.uagb-blockquote__tweet-button svg{width: 15px;height: 15px;}.uagb-block-04b261ae.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button svg{margin-right: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote a.uagb-blockquote__tweet-button{font-size: 15px;}@media only screen and (max-width: 976px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 35px;height: 35px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 20px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 30px;height: 30px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 15px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}.uagb-block-04b261ae .uagb-blockquote__content{font-style: italic;font-size: 18px;line-height: 1.5em;margin-bottom: 25px;text-align: left;}.uagb-block-04b261ae cite.uagb-blockquote__author{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon{width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{width: 25px;height: 25px;fill: #3d3d3d;}.uagb-block-04b261ae.uagb-blockquote__style-style_1 .uagb-blockquote{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 40px;height: 40px;border-radius: 100%;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{fill: #3d3d3d;width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__align-center blockquote.uagb-blockquote{text-align: left;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button svg{fill: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae a.uagb-blockquote__tweet-button svg{width: 15px;height: 15px;}.uagb-block-04b261ae.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button svg{margin-right: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote a.uagb-blockquote__tweet-button{font-size: 15px;}@media only screen and (max-width: 976px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 35px;height: 35px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 20px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 30px;height: 30px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 15px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}.uagb-block-04b261ae .uagb-blockquote__content{font-style: italic;font-size: 18px;line-height: 1.5em;margin-bottom: 25px;text-align: left;}.uagb-block-04b261ae cite.uagb-blockquote__author{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon{width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{width: 25px;height: 25px;fill: #3d3d3d;}.uagb-block-04b261ae.uagb-blockquote__style-style_1 .uagb-blockquote{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 40px;height: 40px;border-radius: 100%;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{fill: #3d3d3d;width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__align-center blockquote.uagb-blockquote{text-align: left;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button svg{fill: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae a.uagb-blockquote__tweet-button svg{width: 15px;height: 15px;}.uagb-block-04b261ae.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button svg{margin-right: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote a.uagb-blockquote__tweet-button{font-size: 15px;}@media only screen and (max-width: 976px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 35px;height: 35px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 20px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 30px;height: 30px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 15px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}.uagb-block-04b261ae .uagb-blockquote__content{font-style: italic;font-size: 18px;line-height: 1.5em;margin-bottom: 25px;text-align: left;}.uagb-block-04b261ae cite.uagb-blockquote__author{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{border-color: #abb8c3;border-left-style: solid;border-left-width: 4px;padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon-wrap{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon{width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon{background: #f4f4f4;border-radius: 100%;margin-bottom: 15px;margin-right: 20px;padding: 10px;}.uagb-block-04b261ae.uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{width: 25px;height: 25px;fill: #3d3d3d;}.uagb-block-04b261ae.uagb-blockquote__style-style_1 .uagb-blockquote{text-align: left;}.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 40px;height: 40px;border-radius: 100%;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;}.uagb-block-04b261ae .uagb-blockquote__skin-quotation .uagb-blockquote__icon svg{fill: #3d3d3d;width: 25px;height: 25px;}.uagb-block-04b261ae.uagb-blockquote__align-center blockquote.uagb-blockquote{text-align: left;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button{color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-link a.uagb-blockquote__tweet-button svg{fill: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button{color: #fff;background-color: #1DA1F2;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button svg{fill: #fff;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae a.uagb-blockquote__tweet-button svg{width: 15px;height: 15px;}.uagb-block-04b261ae.uagb-blockquote__tweet-icon_text a.uagb-blockquote__tweet-button svg{margin-right: 10px;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-classic a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover{background-color: #1DA1F2;}.uagb-block-04b261ae.uagb-blockquote__tweet-style-bubble a.uagb-blockquote__tweet-button:hover:before{border-right-color: #1DA1F2;}.uagb-block-04b261ae .uagb-blockquote a.uagb-blockquote__tweet-button{font-size: 15px;}@media only screen and (max-width: 976px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 35px;height: 35px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 20px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.uagb-block-04b261ae .uagb-blockquote__author-wrap{margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap img{width: 30px;height: 30px;border-radius: 100%;}.uagb-block-04b261ae.uagb-blockquote__skin-border blockquote.uagb-blockquote{padding-left: 15px;}.uagb-block-04b261ae .uagb-blockquote__content{margin-bottom: 15px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-right img{margin-left: 10px;margin-bottom: 0px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-top img{margin-bottom: 10px;}.uagb-block-04b261ae .uagb-blockquote__author-wrap.uagb-blockquote__author-at-left img{margin-right: 10px;margin-bottom: 0px;}}.uagb-cta__outer-wrap .uagb-cta__content,.uagb-cta__outer-wrap a.uagb-cta__block-link span,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__button-wrapper,.uagb-cta__outer-wrap .uagb-cta-typeof-button,.uagb-cta__outer-wrap .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__outer-wrap .uagb-cta-with-svg{display:inline-block}.uagb-cta__outer-wrap{display:flex;justify-content:space-between}.wp-block-uagb-call-to-action .uagb-cta__buttons{display:inline-flex}.wp-block-uagb-call-to-action .wp-block-button__link,.wp-block-uagb-call-to-action .ast-outline-button{fill:currentColor;justify-content:center}.uagb-cta__button-link-wrapper,.uagb-cta-second__button{display:inline-flex;align-items:center;word-break:keep-all;width:100%}.uagb-cta__title{padding:0;margin:0;display:block}.uagb-cta__content-right .uagb-cta__button-wrapper{float:right}.uagb-cta__link-wrapper.uagb-cta__block-link-style:empty{display:none}a.uagb-cta__block-link,.entry .entry-content a.uagb-cta__block-link,a.uagb-cta__block-link-wrap,.entry .entry-content a.uagb-cta__block-link-wrap{text-decoration:none}a.uagb-cta__block-link:hover,.entry .entry-content a.uagb-cta__block-link:hover,a.uagb-cta__block-link-wrap:hover,.entry .entry-content a.uagb-cta__block-link-wrap:hover .entry .entry-content a.uagb-cta__block-link:hover{color:inherit}.uagb-cta__content-right{text-align:right;justify-content:flex-end}.uagb-cta__left-right-wrap{width:100%;word-break:break-word}.uagb-cta__icon-position-below-title .uagb-cta__left-right-wrap{display:block;min-width:100%;width:100%}.uagb-cta__icon-position-left .uagb-cta__left-right-wrap,.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{display:flex}.uagb-cta__icon-position-right .uagb-cta__left-right-wrap{justify-content:flex-end}.uagb-cta__block-link-icon-after{margin-left:5px;margin-right:0}.uagb-cta__block-link-icon-before{margin-left:0;margin-right:5px}.uagb-cta__block-link-icon,.uagb-cta__block svg{transition:all 200ms linear}.uagb-cta__block{position:relative}.uagb-cta-typeof-button{line-height:1;text-align:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link,.uagb-cta__content-right.uagb-cta__button-valign-middle .uagb-cta__left-right-wrap{display:flex;align-items:center}.uagb-cta__content-right .uagb-cta__button-link-wrapper,.uagb-cta__content-right .uagb-cta-second__button .uagb-cta__content-right .uagb-cta__block-link{justify-content:center}.uagb-cta__link-wrapper a{box-shadow:none;text-decoration:none}.uagb-cta__block,.uagb-cta__content,.uagb-cta__left-right-wrap{z-index:1}.uagb-cta__block-link{cursor:pointer}.uagb-cta__content-right .uagb-cta__block-link{float:right;padding:10px 14px}a.uagb-cta__block-link-wrap{color:inherit}.uagb-cta__content p:empty{display:none}.uagb-cta__button-type-none .uagb-cta__content{width:100%}.uagb-cta-with-svg{height:14px;width:14px;line-height:14px;vertical-align:middle}.uagb-cta__block svg{display:block;height:inherit;width:inherit}.uagb-cta__button-link-wrapper svg{width:20px;height:20px}.uagb-cta__align-button-after{margin-left:5px}.uagb-cta__align-button-before{margin-right:5px}.uagb-cta__block-link i{font-style:normal}a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.wp-block-uagb-call-to-action{position:relative}.wp-block-uagb-call-to-action a.uagb-cta__link-to-all{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}@media only screen and (max-width: 976px){.uagb-cta__content-stacked-tablet,.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-tablet .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-tablet.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}@media screen and (max-width: 767px){.uagb-cta__content-stacked-mobile,.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap{flex-direction:column;text-align:center}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__button-wrapper{float:none;margin:0 auto}.uagb-cta__content-stacked-mobile .uagb-cta__left-right-wrap .uagb-cta__content{margin-left:0;margin-right:0}.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content,.uagb-cta__content-stacked-mobile.uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width:100% !important}}.uagb-cta__desc p:last-child{margin-bottom:0}#uagb-cta-block-.wp-block-uagb-call-to-action .uagb-cta__title{margin-bottom: 10px;}#uagb-cta-block-.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 10px;}#uagb-cta-block- .uagb-cta__align-button-after{margin-left: 10px;}#uagb-cta-block- .uagb-cta__align-button-before{margin-right: 10px;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}#uagb-cta-block- .uagb-cta__content-wrap{text-align: left;}#uagb-cta-block- .uagb-cta__wrap{width: 70%;text-align: left;}#uagb-cta-block-.wp-block-uagb-call-to-action{text-align: left;}#uagb-cta-block- .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}#uagb-cta-block- .uagb-cta__buttons{column-gap: 15px;}#uagb-cta-block-.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 70%;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}#uagb-cta-block-.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}#uagb-cta-block- .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: #333;border-style: solid;}#uagb-cta-block-.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;}#uagb-cta-block-.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}@media only screen and (max-width: 976px) {#uagb-cta-block-.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}#uagb-cta-block-.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}#uagb-cta-block- .uagb-cta__wrap{text-align: center;}#uagb-cta-block-.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}}@media only screen and (max-width: 767px) {#uagb-cta-block-.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}#uagb-cta-block-.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}#uagb-cta-block- .uagb-cta__buttons{justify-content: center;}#uagb-cta-block- .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 30%;}#uagb-cta-block- .uagb-cta__wrap{text-align: center;}#uagb-cta-block-.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}}\";s:2:\"js\";s:2302:\"document.addEventListener(\"DOMContentLoaded\", function(){ var selector = document.querySelectorAll( '.uagb-block-04b261ae' );\nif ( selector.length > 0 ) {\n\n\tvar blockquote__tweet = selector[0].getElementsByClassName(\"uagb-blockquote__tweet-button\");\n\n\tif ( blockquote__tweet.length > 0 ) {\n\n\t\tblockquote__tweet[0].addEventListener(\"click\",function(){\t\n\t\t\tvar request_url = \"https:\/\/twitter.com\/intent\/tweet?text=Room+2112%2C+Hanlan+Plaza%2C+No.+23+Ronghe+Road%2C+Guicheng+Street%2C+Nanhai+District%2C+Foshan+City.Guangdong%2C+China+%E2%80%94+Author+Name&url=https%3A%2F%2Fwww.haytrix-display.com%2Ftr%2Ftr%2Fpage%2F4%2F%3Ftrp-form-language%3Dtr%26s\";\n\t\t\twindow.open( request_url );\n\t\t});\n\t}\n}\nvar selector = document.querySelectorAll( '.uagb-block-04b261ae' );\nif ( selector.length > 0 ) {\n\n\tvar blockquote__tweet = selector[0].getElementsByClassName(\"uagb-blockquote__tweet-button\");\n\n\tif ( blockquote__tweet.length > 0 ) {\n\n\t\tblockquote__tweet[0].addEventListener(\"click\",function(){\t\n\t\t\tvar request_url = \"https:\/\/twitter.com\/intent\/tweet?text=sales%40haytrix.com+%E2%80%94+Author+Name&url=https%3A%2F%2Fwww.haytrix-display.com%2Ftr%2Ftr%2Fpage%2F4%2F%3Ftrp-form-language%3Dtr%26s\";\n\t\t\twindow.open( request_url );\n\t\t});\n\t}\n}\nvar selector = document.querySelectorAll( '.uagb-block-04b261ae' );\nif ( selector.length > 0 ) {\n\n\tvar blockquote__tweet = selector[0].getElementsByClassName(\"uagb-blockquote__tweet-button\");\n\n\tif ( blockquote__tweet.length > 0 ) {\n\n\t\tblockquote__tweet[0].addEventListener(\"click\",function(){\t\n\t\t\tvar request_url = \"https:\/\/twitter.com\/intent\/tweet?text=%2B86+123+4567+8910+%E2%80%94+Author+Name&url=https%3A%2F%2Fwww.haytrix-display.com%2Ftr%2Ftr%2Fpage%2F4%2F%3Ftrp-form-language%3Dtr%26s\";\n\t\t\twindow.open( request_url );\n\t\t});\n\t}\n}\nvar selector = document.querySelectorAll( '.uagb-block-04b261ae' );\nif ( selector.length > 0 ) {\n\n\tvar blockquote__tweet = selector[0].getElementsByClassName(\"uagb-blockquote__tweet-button\");\n\n\tif ( blockquote__tweet.length > 0 ) {\n\n\t\tblockquote__tweet[0].addEventListener(\"click\",function(){\t\n\t\t\tvar request_url = \"https:\/\/twitter.com\/intent\/tweet?text=%2B86+123+4567+8910+%E2%80%94+Author+Name&url=https%3A%2F%2Fwww.haytrix-display.com%2Ftr%2Ftr%2Fpage%2F4%2F%3Ftrp-form-language%3Dtr%26s\";\n\t\t\twindow.open( request_url );\n\t\t});\n\t}\n}\n });\";s:18:\"current_block_list\";a:22:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";i:7;s:21:\"uagb\/advanced-heading\";i:8;s:14:\"core\/shortcode\";i:9;s:14:\"core\/page-list\";i:10;s:9:\"core\/list\";i:11;s:14:\"core\/list-item\";i:12;s:26:\"woocommerce\/product-search\";i:13;s:30:\"woocommerce\/product-categories\";i:14;s:17:\"core\/social-links\";i:15;s:16:\"core\/social-link\";i:16;s:14:\"uagb\/container\";i:17;s:14:\"core\/paragraph\";i:18;s:10:\"core\/quote\";i:19;s:12:\"core\/details\";i:20;s:15:\"uagb\/blockquote\";i:21;s:19:\"uagb\/call-to-action\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778612850\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",600,600,false],"thumbnail":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2-150x150.jpg",150,150,true],"medium":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2-300x300.jpg",300,300,true],"medium_large":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",600,600,false],"large":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",600,600,false],"1536x1536":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",600,600,false],"2048x2048":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",600,600,false],"trp-custom-language-flag":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",12,12,false],"woocommerce_thumbnail":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2.jpg",600,600,false],"woocommerce_gallery_thumbnail":["https:\/\/www.haytrix-display.com\/wp-content\/uploads\/2025\/08\/0006_\u4e3b\u56fe1-2-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"info6","author_link":"https:\/\/www.haytrix-display.com\/de\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"The Haytrix M6H display is a durable smart dashboard for e-bikes and e-scooters, using UART No.2 protocol for reliable performance. Designed for manufacturers, distributors, and repair shops.","_links":{"self":[{"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/product\/1960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/comments?post=1960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/media\/1961"}],"wp:attachment":[{"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/media?parent=1960"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/product_brand?post=1960"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/product_cat?post=1960"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.haytrix-display.com\/de\/wp-json\/wp\/v2\/product_tag?post=1960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}